{"id":1018,"date":"2009-10-19T14:50:31","date_gmt":"2009-10-19T12:50:31","guid":{"rendered":"http:\/\/www.idrologia.polito.it\/web2\/?page_id=1018"},"modified":"2009-10-21T17:40:14","modified_gmt":"2009-10-21T15:40:14","slug":"fase3","status":"publish","type":"page","link":"https:\/\/www.idrologia.polito.it\/web2\/ricerca\/invasi-artificiali\/interreg\/fase3\/","title":{"rendered":"FASE 3"},"content":{"rendered":"<p style=\"TEXT-ALIGN: justify\"><span style=\"FONT-SIZE: 10pt; FONT-FAMILY: Verdana\">Presso l\u2019Istituto Scienze della Terra,\u00a0\u00e8 stato\u00a0sviluppato, calibrato e validato un modello afflussi-deflussi distribuito per la simulazione idrologica degli afflussi al lago Verbano e del regime di piena nei bacini minori a valle degli invasi idroelettrici (Bacini: Ticino + Maggia + Verzasca).<\/span><\/p>\n<p style=\"TEXT-ALIGN: justify\"><span style=\"FONT-SIZE: 10pt; FONT-FAMILY: Verdana\">Presso il Politecnico di Torino,\u00a0\u00e8 stato\u00a0sviluppato un modello per la simulazione continua dei deflussi alla scala di uno o pi\u00f9 giorni consecutivi, con caratteristiche tali da consentire la generazione di lunghe serie sintetiche di portate aventi statistiche equivalenti a quelle delle serie originarie. <\/span><\/p>\n<blockquote>\n<p style=\"TEXT-ALIGN: right\"><span style=\"FONT-SIZE: 10pt; FONT-FAMILY: Verdana\"><a href=\"http:\/\/www.idrologia.polito.it\/web2\/progetti\/conclusi\/interreg\/\">Torna ad INTERREG<\/a><\/span><\/p>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p style=\"TEXT-ALIGN: justify\">Presso l\u2019Istituto Scienze della Terra, \u00e8 stato sviluppato, calibrato e validato un modello afflussi-deflussi distribuito per la simulazione idrologica degli afflussi al lago Verbano e del regime di piena nei bacini minori a valle degli invasi idroelettrici (Bacini: Ticino + Maggia + Verzasca).<\/p>\n<p style=\"TEXT-ALIGN: justify\">Presso il Politecnico di Torino, \u00e8 stato sviluppato [&#8230;]<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":992,"menu_order":2,"comment_status":"open","ping_status":"open","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/www.idrologia.polito.it\/web2\/wp-json\/wp\/v2\/pages\/1018"}],"collection":[{"href":"https:\/\/www.idrologia.polito.it\/web2\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.idrologia.polito.it\/web2\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.idrologia.polito.it\/web2\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.idrologia.polito.it\/web2\/wp-json\/wp\/v2\/comments?post=1018"}],"version-history":[{"count":4,"href":"https:\/\/www.idrologia.polito.it\/web2\/wp-json\/wp\/v2\/pages\/1018\/revisions"}],"predecessor-version":[{"id":1020,"href":"https:\/\/www.idrologia.polito.it\/web2\/wp-json\/wp\/v2\/pages\/1018\/revisions\/1020"}],"up":[{"embeddable":true,"href":"https:\/\/www.idrologia.polito.it\/web2\/wp-json\/wp\/v2\/pages\/992"}],"wp:attachment":[{"href":"https:\/\/www.idrologia.polito.it\/web2\/wp-json\/wp\/v2\/media?parent=1018"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}